{"id":8,"count":3,"description":"","link":"https:\/\/chem.sites.mtu.edu\/mazzoleni\/index.php\/category\/people\/","name":"People","slug":"people","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/chem.sites.mtu.edu\/mazzoleni\/index.php\/wp-json\/wp\/v2\/categories\/8","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chem.sites.mtu.edu\/mazzoleni\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/chem.sites.mtu.edu\/mazzoleni\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/chem.sites.mtu.edu\/mazzoleni\/index.php\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}